{"id":4784,"date":"2024-12-14T14:18:36","date_gmt":"2024-12-14T13:18:36","guid":{"rendered":"https:\/\/www.sebastianusschule.de\/wpkgss\/?p=4784"},"modified":"2024-12-14T14:20:51","modified_gmt":"2024-12-14T13:20:51","slug":"tag-der-offenen-tuer-mit-adventsbasar","status":"publish","type":"post","link":"http:\/\/www.sebastianusschule.de\/wpkgss\/tag-der-offenen-tuer-mit-adventsbasar\/","title":{"rendered":"Tag der offenen T\u00fcr mit Adventsbasar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4784\" class=\"elementor elementor-4784\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afdbdcd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afdbdcd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b175ebc\" data-id=\"b175ebc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-456cbe6 elementor-widget elementor-widget-text-editor\" data-id=\"456cbe6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Schon ein paar Minuten vor halb neun warteten interessierte Eltern der neuen Erstkl\u00e4ssler geduldig vor den Toren der Sebastianusschule. Kurz darauf betraten sie voller Neugierde das Geb\u00e4ude und ihre Erwartungen wurden nicht entt\u00e4uscht.<\/p><p>Erste Eindr\u00fccke in die Arbeit der KGS erhielten die G\u00e4ste durch Unterrichtspr\u00e4sentationen in der ersten und zweiten Klasse, wo Einblicke in den lebendigen Deutsch- und Geometrieunterricht m\u00f6glich wurden. Dar\u00fcber hinaus war die gesamte Schule voller bunter Mitmach- und Schnupperangebote, wie z. B. Singen, Basteln und Malen. In der Turnhalle gab es einen sportlichen Mitmachparcours.<\/p><p>Ein H\u00f6hepunkt war nach dem gemeinsamen Singen im Treppenhaus sicherlich der Verkauf der Weihnachtsartikel vom diesj\u00e4hrigen Basteltag der Sebastianuskinder. Auch in der OGS Lernzeit und der Betreuung wurde flei\u00dfig weiter gewerkelt. Beim Adventsbasar waren h\u00fcbsche Teelichter, Weihnachtsbaumanh\u00e4nger, Gru\u00dfkarten und Vieles mehr im Angebot.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9538d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9538d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2af108a\" data-id=\"2af108a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6571f6 elementor-widget elementor-widget-text-editor\" data-id=\"f6571f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Auch f\u00fcr das leibliche Wohl war bestens gesorgt: Mit Sebastianustalern ger\u00fcstet erfreuten sich die Kleinen am Kauf von Muffins, w\u00e4hrend es sich die Gro\u00dfen am Buffet im zweckentfremdeten Teamzimmer und im Forum gut gehen lie\u00dfen. Der Duft von frischgebackenen Waffeln lockte in einen Raum, in dem sich auch der F\u00f6rderverein und die Betreuung digital pr\u00e4sentierten. In diesem Jahr durften wir eine besonders hohe Anzahl an G\u00e4sten willkommen hei\u00dfen; wir hoffen, die kleinen G\u00e4ste mit ihrem gro\u00dfen Anhang im Sommer im neuen Schuljahr wiederzusehen!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Schon ein paar Minuten vor halb neun warteten interessierte Eltern der neuen Erstkl\u00e4ssler geduldig vor den Toren der Sebastianusschule. Kurz darauf betraten sie voller Neugierde das Geb\u00e4ude und ihre Erwartungen wurden nicht entt\u00e4uscht. Erste Eindr\u00fccke in die Arbeit der KGS erhielten die G\u00e4ste durch Unterrichtspr\u00e4sentationen in der ersten und zweiten Klasse, wo Einblicke in den [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/posts\/4784"}],"collection":[{"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/comments?post=4784"}],"version-history":[{"count":4,"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/posts\/4784\/revisions"}],"predecessor-version":[{"id":4788,"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/posts\/4784\/revisions\/4788"}],"wp:attachment":[{"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/media?parent=4784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/categories?post=4784"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sebastianusschule.de\/wpkgss\/wp-json\/wp\/v2\/tags?post=4784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}